{"id":121,"date":"2023-09-03T14:06:50","date_gmt":"2023-09-03T12:06:50","guid":{"rendered":"https:\/\/detenteyquelonnaise.fr\/?p=121"},"modified":"2026-03-06T18:31:33","modified_gmt":"2026-03-06T17:31:33","slug":"calligraphie","status":"publish","type":"post","link":"https:\/\/detenteyquelonnaise.fr\/index.php\/2023\/09\/03\/calligraphie\/","title":{"rendered":"CALLIGRAPHIE"},"content":{"rendered":"\n<p>Cours de Calligraphie occidentale<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2023\/09\/20260110_113812-1-576x1024.jpg\" alt=\"\" class=\"wp-image-429\" srcset=\"https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2023\/09\/20260110_113812-1-576x1024.jpg 576w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2023\/09\/20260110_113812-1-169x300.jpg 169w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2023\/09\/20260110_113812-1-768x1365.jpg 768w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2023\/09\/20260110_113812-1-864x1536.jpg 864w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2023\/09\/20260110_113812-1-1152x2048.jpg 1152w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2023\/09\/20260110_113812-1.jpg 1440w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure>\n\n\n\n<p><strong>Les mercredis de 18 h \u00e0 20 h ( \u00e0 la mairie d&rsquo;Yquelon)<\/strong><\/p>\n\n\n\n<p><strong>D\u00e9but des cours<\/strong>&nbsp;<strong>: le mercredi 17 septembre<\/strong> <strong>2025<\/strong> ( 1er cours gratuit )<\/p>\n\n\n\n<p><strong>Association<\/strong>&nbsp;: D\u00e9tente Yquelonnaise<\/p>\n\n\n\n<p><strong>Contact<\/strong>&nbsp;: Elisabeth GUAMIS \u2013 06 75 15 53 83<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"853\" height=\"712\" src=\"https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2023\/09\/image.png\" alt=\"\" class=\"wp-image-418\" srcset=\"https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2023\/09\/image.png 853w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2023\/09\/image-300x250.png 300w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2023\/09\/image-768x641.png 768w\" sizes=\"auto, (max-width: 853px) 100vw, 853px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"http:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2024\/01\/20241219_114055-1024x768.jpg\" alt=\"\" class=\"wp-image-270\" srcset=\"https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2024\/01\/20241219_114055-1024x768.jpg 1024w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2024\/01\/20241219_114055-300x225.jpg 300w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2024\/01\/20241219_114055-768x576.jpg 768w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2024\/01\/20241219_114055-1536x1152.jpg 1536w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2024\/01\/20241219_114055-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Les cours ont lieu le mercredi de 18 \u00e0 20 h dans la salle des commissions au premier \u00e9tage derri\u00e8re la mairie d&rsquo;Yquelon.<\/p>\n\n\n\n<p>La calligraphie est l&rsquo;art de la belle \u00e9criture. Elle se pratique avec des plumes de taille diff\u00e9rente et des porte-plumes, mais on peut la pratiquer aussi avec des pinceaux et toutes sortes d&rsquo;outils plus modernes puisque les calligraphes ont cr\u00e9e des calligraphies contemporaines. La calligraphie am\u00e9liore la concentration, l&rsquo;attention, l&rsquo;observation. Elle agit un peu comme une sorte de m\u00e9ditation. Elle permet de faire de belles lettres avec les pleins et les d\u00e9li\u00e9s et on peut l&rsquo;utiliser pour \u00e9crire&nbsp; des faire-part, des cartes d&rsquo;invitation, des menus, etc..<\/p>\n\n\n\n<p>Contact E Guamis 06 75 15 53 83 <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"http:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2023\/09\/20241218_185814-768x1024.jpg\" alt=\"\" class=\"wp-image-285\" srcset=\"https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2023\/09\/20241218_185814-768x1024.jpg 768w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2023\/09\/20241218_185814-225x300.jpg 225w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2023\/09\/20241218_185814-1152x1536.jpg 1152w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2023\/09\/20241218_185814-1536x2048.jpg 1536w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2023\/09\/20241218_185814-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2023\/09\/flyer-2024.pdf\" type=\"application\/pdf\" style=\"width:100%;height:670px\" aria-label=\"Contenu embarqu\u00e9 flyer 2024.\"><\/object><a id=\"wp-block-file--media-ceb93112-aafc-477a-b480-dc79edd90334\" href=\"https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2023\/09\/flyer-2024.pdf\">flyer 2024<\/a><a href=\"https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2023\/09\/flyer-2024.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-ceb93112-aafc-477a-b480-dc79edd90334\">T\u00e9l\u00e9charger<\/a><\/div>\n\n\n\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-9c69f0ab-ee77-4ce8-98ef-e60b286e0273\" href=\"https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2024\/02\/20240207_180953-scaled.jpg\">20240207_180953<\/a><a href=\"https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2024\/02\/20240207_180953-scaled.jpg\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-9c69f0ab-ee77-4ce8-98ef-e60b286e0273\">T\u00e9l\u00e9charger<\/a><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2024\/02\/20240207_180953-1-1024x768.jpg\" alt=\"\" class=\"wp-image-192\" srcset=\"https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2024\/02\/20240207_180953-1-1024x768.jpg 1024w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2024\/02\/20240207_180953-1-300x225.jpg 300w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2024\/02\/20240207_180953-1-768x576.jpg 768w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2024\/02\/20240207_180953-1-1536x1152.jpg 1536w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2024\/02\/20240207_180953-1-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2024\/02\/20240207_181917-1024x768.jpg\" alt=\"\" class=\"wp-image-193\" srcset=\"https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2024\/02\/20240207_181917-1024x768.jpg 1024w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2024\/02\/20240207_181917-300x225.jpg 300w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2024\/02\/20240207_181917-768x576.jpg 768w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2024\/02\/20240207_181917-1536x1152.jpg 1536w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2024\/02\/20240207_181917-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"659\" src=\"https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2023\/09\/CALLI-1-1024x659.jpg\" alt=\"\" class=\"wp-image-471\" srcset=\"https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2023\/09\/CALLI-1-1024x659.jpg 1024w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2023\/09\/CALLI-1-300x193.jpg 300w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2023\/09\/CALLI-1-768x495.jpg 768w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2023\/09\/CALLI-1.jpg 1118w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Cours de Calligraphie occidentale Les mercredis de 18 h \u00e0 20 h ( \u00e0 la mairie d&rsquo;Yquelon) D\u00e9but des cours&nbsp;: le mercredi 17 septembre 2025 ( 1er cours gratuit ) Association&nbsp;: D\u00e9tente Yquelonnaise Contact&nbsp;: Elisabeth GUAMIS \u2013 06 75 15 53 83 Les cours ont lieu le mercredi de 18 \u00e0 20 h dans la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":429,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-121","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/detenteyquelonnaise.fr\/index.php\/wp-json\/wp\/v2\/posts\/121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/detenteyquelonnaise.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/detenteyquelonnaise.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/detenteyquelonnaise.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/detenteyquelonnaise.fr\/index.php\/wp-json\/wp\/v2\/comments?post=121"}],"version-history":[{"count":11,"href":"https:\/\/detenteyquelonnaise.fr\/index.php\/wp-json\/wp\/v2\/posts\/121\/revisions"}],"predecessor-version":[{"id":472,"href":"https:\/\/detenteyquelonnaise.fr\/index.php\/wp-json\/wp\/v2\/posts\/121\/revisions\/472"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/detenteyquelonnaise.fr\/index.php\/wp-json\/wp\/v2\/media\/429"}],"wp:attachment":[{"href":"https:\/\/detenteyquelonnaise.fr\/index.php\/wp-json\/wp\/v2\/media?parent=121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/detenteyquelonnaise.fr\/index.php\/wp-json\/wp\/v2\/categories?post=121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/detenteyquelonnaise.fr\/index.php\/wp-json\/wp\/v2\/tags?post=121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}