{"id":545,"date":"2026-09-01T17:34:36","date_gmt":"2026-09-01T15:34:36","guid":{"rendered":"https:\/\/detenteyquelonnaise.fr\/?p=545"},"modified":"2026-09-01T17:39:51","modified_gmt":"2026-09-01T15:39:51","slug":"atelier-tricot-et-crochet","status":"publish","type":"post","link":"https:\/\/detenteyquelonnaise.fr\/index.php\/2026\/09\/01\/atelier-tricot-et-crochet\/","title":{"rendered":"ATELIER TRICOT ET CROCHET"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>ATELIER TRICOT<\/strong>  <strong>\u00a0ET CROCHET<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Andr\u00e9e aura le plaisir de vous accueillir \u00a0\u00a0A <strong>la Grange Dimi\u00e8re \u00e0 Yquelon \u00a0<\/strong>(Dans la cour de la mairie)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0<strong>Les mercredis de 18h \u00e0 20h tous les 15 jours \u00a0\u00a0\u00c0 partir du 16 septembre 2026<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elle pourra vous aider et vous conseiller dans vos projets de tricot et de crochet. <strong>Atelier gratuit<\/strong>, adh\u00e9sion de 6 euros <a>\u00e0 l\u2019association de la D\u00e9tente Yquelonnaise.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contact : 06 30 88 78 91 ou&nbsp;detenteyquelonnaise@gmail.com<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Site&nbsp;: <a href=\"http:\/\/www.detenteyquelonnaise.fr\/\">www.detenteyquelonnaise<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-d54931b9-c900-4c8c-8e44-b19769ba61ac\" href=\"https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2026\/09\/affiche-.pptx\">affiche<\/a><a href=\"https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2026\/09\/affiche-.pptx\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-d54931b9-c900-4c8c-8e44-b19769ba61ac\">T\u00e9l\u00e9charger<\/a><\/div>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"927\" src=\"https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2026\/09\/dentelle-1024x927.jpg\" alt=\"\" class=\"wp-image-552\" style=\"aspect-ratio:1.1046404829864975;width:751px;height:auto\" srcset=\"https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2026\/09\/dentelle-1024x927.jpg 1024w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2026\/09\/dentelle-300x272.jpg 300w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2026\/09\/dentelle-768x695.jpg 768w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2026\/09\/dentelle-1536x1391.jpg 1536w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2026\/09\/dentelle.jpg 2006w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"513\" src=\"https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2026\/09\/gilet-1024x513.jpg\" alt=\"\" class=\"wp-image-548\" srcset=\"https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2026\/09\/gilet-1024x513.jpg 1024w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2026\/09\/gilet-300x150.jpg 300w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2026\/09\/gilet-768x385.jpg 768w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2026\/09\/gilet-1536x770.jpg 1536w, https:\/\/detenteyquelonnaise.fr\/wp-content\/uploads\/2026\/09\/gilet-2048x1026.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>ATELIER TRICOT \u00a0ET CROCHET Andr\u00e9e aura le plaisir de vous accueillir \u00a0\u00a0A la Grange Dimi\u00e8re \u00e0 Yquelon \u00a0(Dans la cour de la mairie) \u00a0Les mercredis de 18h \u00e0 20h tous les 15 jours \u00a0\u00a0\u00c0 partir du 16 septembre 2026 Elle pourra vous aider et vous conseiller dans vos projets de tricot et de crochet. Atelier [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":547,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-545","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/detenteyquelonnaise.fr\/index.php\/wp-json\/wp\/v2\/posts\/545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/detenteyquelonnaise.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/detenteyquelonnaise.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/detenteyquelonnaise.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/detenteyquelonnaise.fr\/index.php\/wp-json\/wp\/v2\/comments?post=545"}],"version-history":[{"count":4,"href":"https:\/\/detenteyquelonnaise.fr\/index.php\/wp-json\/wp\/v2\/posts\/545\/revisions"}],"predecessor-version":[{"id":553,"href":"https:\/\/detenteyquelonnaise.fr\/index.php\/wp-json\/wp\/v2\/posts\/545\/revisions\/553"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/detenteyquelonnaise.fr\/index.php\/wp-json\/wp\/v2\/media\/547"}],"wp:attachment":[{"href":"https:\/\/detenteyquelonnaise.fr\/index.php\/wp-json\/wp\/v2\/media?parent=545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/detenteyquelonnaise.fr\/index.php\/wp-json\/wp\/v2\/categories?post=545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/detenteyquelonnaise.fr\/index.php\/wp-json\/wp\/v2\/tags?post=545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}